{"id":194,"date":"2022-09-30T21:49:00","date_gmt":"2022-09-30T19:49:00","guid":{"rendered":"https:\/\/emosovo.psoni.org.pl\/?p=194"},"modified":"2023-03-02T21:51:40","modified_gmt":"2023-03-02T20:51:40","slug":"reunion-organizativa-celebrada-en-madrid","status":"publish","type":"post","link":"https:\/\/emosovo.psoni.org.pl\/index.php\/es\/2022\/09\/30\/reunion-organizativa-celebrada-en-madrid\/","title":{"rendered":"Reuni\u00f3n organizativa, celebrada en Madrid"},"content":{"rendered":"\n<p>El 28 de septiembre de 2022, tuvo lugar la Reuni\u00f3n de organizaci\u00f3n antes de la siguiente fase del Proyecto EmoSovo. Asistieron a la reuni\u00f3n representantes de la entidad espa\u00f1ola del Grupo Fundaci\u00f3n San Cebrian, Leonor Ramos Wilson e Ireneo Martin, as\u00ed como \u00c1gata Jachura de los Talleres de Terapia Ocupacional de la Asociaci\u00f3n Polaca para Personas con Discapacidad Intelectual en Biskupiec y Joanna Lisota de la Oficina PSONI en Varsovia.<\/p>\n\n\n\n<p>Los representantes de ambas organizaciones participantes en el Proyecto EmoSovo se reunieron por primera vez.<\/p>\n\n\n\n<p>Durante la reunion, analizaron las siguientes actividades del Proyecto entre las dos organizaciones y sus dos radios inclusivas: Radio Emocionate y Radio Polaca SoVo.<\/p>\n\n\n\n<p>Se planificaron las siguientes etapas del proyecto y las tareas que corresponder a cada socio. Esta reunion fue una muy buena introducci\u00f3n al desarrollo de la cooperaci\u00f3n durante la ejecuci\u00f3n de las tareas en el proyecto.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"190\" src=\"https:\/\/emosovo.psoni.org.pl\/wp-content\/uploads\/2023\/03\/Robocze-spotkanie-w-Madrycie3-1024x768.jpg\" alt=\"\" class=\"wp-image-190\" srcset=\"https:\/\/emosovo.psoni.org.pl\/wp-content\/uploads\/2023\/03\/Robocze-spotkanie-w-Madrycie3-1024x768.jpg 1024w, https:\/\/emosovo.psoni.org.pl\/wp-content\/uploads\/2023\/03\/Robocze-spotkanie-w-Madrycie3-300x225.jpg 300w, https:\/\/emosovo.psoni.org.pl\/wp-content\/uploads\/2023\/03\/Robocze-spotkanie-w-Madrycie3-768x576.jpg 768w, https:\/\/emosovo.psoni.org.pl\/wp-content\/uploads\/2023\/03\/Robocze-spotkanie-w-Madrycie3-1536x1152.jpg 1536w, https:\/\/emosovo.psoni.org.pl\/wp-content\/uploads\/2023\/03\/Robocze-spotkanie-w-Madrycie3-1140x855.jpg 1140w, https:\/\/emosovo.psoni.org.pl\/wp-content\/uploads\/2023\/03\/Robocze-spotkanie-w-Madrycie3.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" data-id=\"189\" src=\"https:\/\/emosovo.psoni.org.pl\/wp-content\/uploads\/2023\/03\/Robocze-spotkanie-w-Madrycie2-768x1024.jpg\" alt=\"\" class=\"wp-image-189\" srcset=\"https:\/\/emosovo.psoni.org.pl\/wp-content\/uploads\/2023\/03\/Robocze-spotkanie-w-Madrycie2-768x1024.jpg 768w, https:\/\/emosovo.psoni.org.pl\/wp-content\/uploads\/2023\/03\/Robocze-spotkanie-w-Madrycie2-225x300.jpg 225w, https:\/\/emosovo.psoni.org.pl\/wp-content\/uploads\/2023\/03\/Robocze-spotkanie-w-Madrycie2-1152x1536.jpg 1152w, https:\/\/emosovo.psoni.org.pl\/wp-content\/uploads\/2023\/03\/Robocze-spotkanie-w-Madrycie2-1140x1520.jpg 1140w, https:\/\/emosovo.psoni.org.pl\/wp-content\/uploads\/2023\/03\/Robocze-spotkanie-w-Madrycie2.jpg 1500w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El 28 de septiembre de 2022, tuvo lugar la Reuni\u00f3n de organizaci\u00f3n antes de la siguiente fase del Proyecto EmoSovo. Asistieron a la reuni\u00f3n representantes de la entidad espa\u00f1ola del Grupo Fundaci\u00f3n San Cebrian, Leonor Ramos Wilson e Ireneo Martin, as\u00ed como \u00c1gata Jachura de los Talleres de Terapia Ocupacional de la Asociaci\u00f3n Polaca para Personas con Discapacidad Intelectual en Biskupiec y Joanna Lisota de la Oficina PSONI en Varsovia. Los representantes de ambas organizaciones participantes en el Proyecto EmoSovo se reunieron por primera vez. Durante la reunion, analizaron las siguientes actividades del Proyecto entre las dos organizaciones y sus dos radios inclusivas: Radio Emocionate y Radio Polaca SoVo. Se planificaron las siguientes etapas del proyecto y las tareas que corresponder a cada socio. Esta reunion fue una muy buena introducci\u00f3n al desarrollo de la cooperaci\u00f3n durante la ejecuci\u00f3n de las tareas en el proyecto.<\/p>\n","protected":false},"author":1,"featured_media":189,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"class_list":["post-194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos"],"_links":{"self":[{"href":"https:\/\/emosovo.psoni.org.pl\/index.php\/wp-json\/wp\/v2\/posts\/194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emosovo.psoni.org.pl\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emosovo.psoni.org.pl\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emosovo.psoni.org.pl\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emosovo.psoni.org.pl\/index.php\/wp-json\/wp\/v2\/comments?post=194"}],"version-history":[{"count":1,"href":"https:\/\/emosovo.psoni.org.pl\/index.php\/wp-json\/wp\/v2\/posts\/194\/revisions"}],"predecessor-version":[{"id":195,"href":"https:\/\/emosovo.psoni.org.pl\/index.php\/wp-json\/wp\/v2\/posts\/194\/revisions\/195"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emosovo.psoni.org.pl\/index.php\/wp-json\/wp\/v2\/media\/189"}],"wp:attachment":[{"href":"https:\/\/emosovo.psoni.org.pl\/index.php\/wp-json\/wp\/v2\/media?parent=194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emosovo.psoni.org.pl\/index.php\/wp-json\/wp\/v2\/categories?post=194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emosovo.psoni.org.pl\/index.php\/wp-json\/wp\/v2\/tags?post=194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}